{"id":1011,"date":"2013-02-13T04:36:28","date_gmt":"2013-02-13T04:36:28","guid":{"rendered":"http:\/\/vasquezabogados.com\/estudio\/?p=1011"},"modified":"2020-06-23T15:34:38","modified_gmt":"2020-06-23T15:34:38","slug":"abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad","status":"publish","type":"post","link":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/","title":{"rendered":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&nbsp;<strong>Por Marlio V\u00e1squez V\u00e1squez<\/strong><br>Socio de <strong>VASQUEZ | TAFUR<\/strong> <strong>Abogado<\/strong>s<br>Miembro de Peruvian Legal Network<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&nbsp;<\/strong><strong>Utilidad.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El presente comentario explica las posibilidades de archivamiento de una denuncia o proceso penal en base a un acuerdo entre las partes involucradas, logrando que la voluntad entre v\u00edctima y agresor pongan fin a la acci\u00f3n penal que com\u00fanmente se entend\u00eda como imparable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>INTRODUCCI\u00d3N<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro sistema penal durante a\u00f1os impidi\u00f3 que las denuncias interpuestas por la comisi\u00f3n de delitos sean paralizadas en su tramitaci\u00f3n. El criterio uniforme que operadores del derecho y sociedad en general entend\u00edan, era que interpuesta una denuncia, \u00e9sta deb\u00eda continuar hasta la emisi\u00f3n de una sentencia sin posibilidad de que las partes puedan decidir&nbsp; por su suspensi\u00f3n o terminaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de 1991 con la promulgaci\u00f3n de un nuevo C\u00f3digo Procesal Penal, el criterio cambi\u00f3 bajo la incorporaci\u00f3n del denominado \u201cprincipio de oportunidad\u201d de la cual la \u201cabstenci\u00f3n del ejercicio de la acci\u00f3n penal\u201d es una de sus manifestaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El C\u00f3digo Procesal Penal de 1991 y el C\u00f3digo Procesal Penal del 2004 que ya rige el procedimiento penal en varios distritos judiciales y pronto regir\u00e1 en todo el territorio nacional, estableci\u00f3 la facultad del Ministerio P\u00fablico para decidir la abstenci\u00f3n del ejercicio de la acci\u00f3n penal o promover el sobreseimiento de la acci\u00f3n penal ya iniciada, figura procesal que ha venido a acu\u00f1arse entre nosotros con el nombre de \u201cprincipio de oportunidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a que en nuestro medio se han dedicado muchas l\u00edneas a \u00e9sta figura procesal, el tema no parece aun agotado y menos aun entendido cabalmente, lo que ha llevado a la emisi\u00f3n de circulares&nbsp; al seno del Ministerio P\u00fablico bajo la intenci\u00f3n de constituirse en elementos orientadores para su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erradamente se ha venido llamando principio de oportunidad a lo que solamente constituye&nbsp; una manifestaci\u00f3n de \u00e9ste principio; error que se ha generado en la arbitraria sumilla incluida en las publicaciones particulares del texto procesal. El texto virgen del C\u00f3digo Procesal Penal promulgado por el legislador de 1991 nunca identific\u00f3 el art\u00edculo 2 con el nombre de \u00a8principio de oportunidad\u00a8, limit\u00e1ndose \u00fanicamente a la descripci\u00f3n del supuesto procesal que en dicho art\u00edculo est\u00e1 contenido. A partir de estas arbitrarias sumillas que las publicaciones particulares imprim\u00edan con el objeto loable de identificar el contenido de la norma, se empez\u00f3&nbsp; a llamar \u00a8 principio de oportunidad \u00a8 en nuestra doctrina y pr\u00e1ctica judicial al supuesto contenido en el Art\u00edculo 2 del C\u00f3digo Procesal Penal, denominaci\u00f3n que se ha recogido en disposiciones de menor jerarqu\u00eda como en la Circular No. 006-95-MP-FN aprobada por la Resoluci\u00f3n 1072-95 del 15 &nbsp;noviembre de 1995&nbsp; y en la Resoluci\u00f3n No. 200-2001-CT-MP del Consejo Transitorio del Ministerio P\u00fablico de abril del 2001 y su modificatoria la Resoluci\u00f3n No.266-2001-CT-MP del 27 de abril 2001<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un proceso penal regido por el principio de legalidad prohibe la posibilidad de renuncia al ejercicio de la acci\u00f3n penal, el desistimiento de la acci\u00f3n o la transacci\u00f3n con el imputado. Pero un sistema procesal que aplique rigurosamente el principio de legalidad, resulta en muchos casos contrario a la verificaci\u00f3n de la justicia material, por lo que las legislaciones actuales introducen ciertas excepciones que otorgan discrecionalidad&nbsp; en el ejercicio y continuidad de la persecuci\u00f3n penal. Estas excepciones al principio de legalidad se \u201cacostumbran resumir bajo la expresi\u00f3n gen\u00e9rica de <strong>principio de oportunidad\u201d (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn1\"><strong>[1]<\/strong><\/a>).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un sistema procesal que por el contrario acoge el principio de oportunidad, supone&nbsp; la posibilidad de que los \u00f3rganos p\u00fablicos a quienes se les encomienda la persecuci\u00f3n penal prescindan de ella por motivos de utilidad social o razones pol\u00edtico criminales (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn2\">[2]<\/a>). El principio de oportunidad en el sistema procesal penal, se manifiesta, ya sea mediante la posibilidad de abstenci\u00f3n del ejercicio de la acci\u00f3n penal o el sobreseimiento de la acci\u00f3n ya iniciada (Art. 2 del nuevo C\u00f3digo Procesal Penal), la terminaci\u00f3n anticipada del proceso o la eximente o reducci\u00f3n de pena por colaboraci\u00f3n eficaz en delitos en agravio del Estado. Todos estos son criterios de oportunidad introducidos en nuestro sistema legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No resulta del todo correcto en consecuencia llamar al supuesto procesal contenido en el art\u00edculo 2 del Nuevo C\u00f3digo Procesal Penal con el r\u00f3tulo de Principio de Oportunidad, cuando est\u00e1 referido m\u00e1s propiamente a la abstenci\u00f3n en el ejercicio de la acci\u00f3n penal o sobreseimiento de la acci\u00f3n ya iniciada, que vienen a constituir s\u00f3lo algunas&nbsp; manifestaciones del principio de oportunidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>LOS SUPUESTOS DE PROCEDENCIA PARA LA ABSTENCION.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La abstenci\u00f3n al ejercicio de la acci\u00f3n penal puede darse en dos momentos o estados procesales distintos. La abstenci\u00f3n puede suceder antes que el fiscal formalice denuncia ante el Poder&nbsp; Judicial (antes de la disposici\u00f3n de formalizaci\u00f3n de la investigaci\u00f3n preliminar conforme al procedimiento del nuevo CPP), en cuyo caso estamos frente a una <strong>renuncia al ejercicio de la acci\u00f3n penal <\/strong>que no requer\u00eda ser sometido al control de la autoridad judicial. La abstenci\u00f3n puede suceder tambi\u00e9n despu\u00e9s de haberse formalizado la denuncia penal (despu\u00e9s de la disposici\u00f3n de formalizaci\u00f3n de la investigaci\u00f3n<br>preliminar conforme al procedimiento del nuevo CPP), en cuyo caso hay una <strong>renuncia a la continuidad del ejercicio de la acci\u00f3n penal<\/strong> y la aplicaci\u00f3n del principio requerir\u00e1 control de la autoridad judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos momentos o estados procesales, los requisitos de procedencia para la abstenci\u00f3n de la acci\u00f3n penal son id\u00e9nticos, variando \u00fanicamente el procedimiento para su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La norma procesal comprende tres supuestos distintos para la procedencia de la abstenci\u00f3n del ejercicio de la acci\u00f3n penal comprendidos bajo dos criterios: <strong>Falta de necesidad de pena<\/strong> y <strong>Falta de merecimiento de pena<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FALTA DE NECESIDAD DE PENA<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El Inc. 1 del Art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991 plantea la abstenci\u00f3n de la acci\u00f3n penal, cuando la pena a imponerse resulte innecesaria frente a los graves efectos del delito reca\u00eddos sobre el autor del mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Derecho Penal Alem\u00e1n, de donde el precepto proviene bajo la figura de dispensa de pena (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn3\">[3]<\/a>), se gener\u00f3 la norma a partir de casos de accidentes de tr\u00e1nsito cometidos por comportamientos culposos en los que el hecho delictivo gener\u00f3 grave da\u00f1o al conductor o a sus acompa\u00f1antes con quienes manten\u00eda un lazo familiar cercano, considerando los tribunales de justicia&nbsp; que en esos casos el da\u00f1o directo o indirecto sufrido tendr\u00eda mayor valor sancionatorio que la imposici\u00f3n de la pena aplicable que frente a ese resultado terminaba convirti\u00e9ndose en innecesaria y desproporcionada (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn4\">[4]<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo el texto de la norma procesal, tanto la del C\u00f3digo Procesal de 1991, como la del C\u00f3digo Procesal Penal del 2004, la abstenci\u00f3n sin embargo no debe operar simplemente por la producci\u00f3n de las graves consecuencias sobre el agente, es necesario adem\u00e1s que frente a ese resultado la pena devenga en inapropiada. Esta condici\u00f3n de falta de necesidad de pena o que la \u201cpena resulte inapropiada o innecesaria\u201d para emplear los t\u00e9rminos de las normas en menci\u00f3n, no se constituye autom\u00e1ticamente por la producci\u00f3n de la grave consecuencia generada por el delito sobre el agente, abriendo un amplio margen de discrecionalidad en el que habr\u00e1 que determinar lo inapropiado o falta de necesidad de la pena teniendo en consideraci\u00f3n su ineficacia desde el punto de vista de la prevenci\u00f3n general y especial. Es decir, frente a las graves consecuencias del delito reca\u00eddas sobre el agente, la pena debe haber perdido sentido en todas sus funciones (compensaci\u00f3n del injusto y de la culpabilidad \u2013 prevenci\u00f3n general y prevenci\u00f3n especial).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp; determinaci\u00f3n de cuando una pena resulta inapropiada, no est\u00e1 as\u00ed derivada \u00fanicamente de la&nbsp; producci\u00f3n del resultado o consecuencia grave sobre el agente, sino que esa determinaci\u00f3n&nbsp; se basa en un conjunto de objetivos en los que la pena est\u00e1 llamada a cumplir (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn5\">[5]<\/a>). Por ejemplo parece claramente inapropiada la pena&nbsp; en el caso del conductor culposo que excedi\u00e9ndose en la velocidad permitida produce en una curva la volcadura de su veh\u00edculo en el cual fallece su menor hijo. En este supuesto, el efecto preventivo especial y general de la pena, as\u00ed&nbsp; como la compensaci\u00f3n por el injusto y la culpabilidad del agente parecen razonadamente cumplidos con el da\u00f1o grave sufrido y la abstenci\u00f3n resulta entendida. No parece sin embargo que la compensaci\u00f3n del injusto y la culpabilidad del agente resulte cumplida en el caso del conductor, que conduciendo en una v\u00eda de doble sentido&nbsp; a excesiva velocidad e invadiendo el carril contrario para sobrepasar a otros veh\u00edculos, causa un accidente generando la volcadura de otros veh\u00edculos causando la muerte de unos y poniendo en riesgo la vida de otros, aun cuando el agente resulte de ello con la p\u00e9rdida de uno de sus extremidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La justicia penal alemana, de donde la norma proviene, entendi\u00f3 que la producci\u00f3n del grave da\u00f1o al agente no es la que autom\u00e1ticamente genera la falta de necesidad de la pena. Este es tambi\u00e9n el sentido del texto procesal nacional cuando en la norma se condiciona la abstenci\u00f3n de la acci\u00f3n penal a la existencia de dos situaciones: 1ero. Producci\u00f3n de grave da\u00f1o al agente \u201cy\u201d, 2do. Que la pena resulte inapropiada o innecesaria. Si el sentido de la norma procesal nacional fuese, que la falta de necesidad de pena se genera autom\u00e1ticamente por la producci\u00f3n del grave da\u00f1o al agente, no tendr\u00eda entonces sentido la segunda parte del precepto que se mantiene en ambos textos procesales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es tambi\u00e9n el sentido (aunque no claramente explicado que lo hace devenir en incomprensible) de la directiva o criterio plasmado en el literal e), numeral 8 de la Circular No. 006-95-MP-FN emitida por la Fiscal\u00eda de la Naci\u00f3n en noviembre de 1995 que al referirse a los requisitos a los que est\u00e1 condicionada la abstenci\u00f3n de la acci\u00f3n penal por falta de necesidad de pena del Inc. 1 del Art. 2 del C\u00f3digo Procesal, expresa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201ce) <em>Lo m\u00e1s importante es llegar a la conclusi\u00f3n de que la grave afectaci\u00f3n que el delito ha producido en el propio denunciado o implicado hace innecesario acudir a la sanci\u00f3n penal. Se debe considerar que las razones que fundamentan y legitiman la aplicaci\u00f3n de la pena, vinculadas tanto a la compensaci\u00f3n jur\u00eddico-penal por el delito perpetrado y al grado de culpabilidad puesto en su comisi\u00f3n, cuanto a la prevenci\u00f3n general como especial, resultan inaplicables en el presente caso<\/em>: <em>La pena en raz\u00f3n al padecimiento del imputado por su propia conducta, resultar\u00eda manifiestamente desproporcionada<\/em>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El grave da\u00f1o al agente<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El texto original del Inc. 1 del Art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991, establec\u00eda: \u201c\u2026<em>que el agente haya sido afectado <strong>directa<\/strong> y gravemente por las consecuencias de su delito\u2026<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque en nuestra doctrina el precepto fue entendido en el sentido que el t\u00e9rmino \u201cdirecto\u201d a que hace referencia el texto legal no significaba necesariamente que el grave da\u00f1o debe recaer exclusivamente en el agente, sin &nbsp;excluir los casos de grave da\u00f1o a sus parientes cercanos, sino comprendiendo ambos supuestos (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn6\">[6]<\/a>); parece sin embargo que al seno del Ministerio P\u00fablico, a quien en primer t\u00e9rmino corresponde la aplicaci\u00f3n de esta norma, se crearon dudas en su interpretaci\u00f3n, dando lugar a la Circular No. 006-95-MP-FN de noviembre de 1995 que en &nbsp;el literal c) del numeral 8 precisa que el fiscal deber\u00e1 tomar en consideraci\u00f3n que el da\u00f1o \u201c<em>debe afectar directamente al imputado, es decir, a sus propios bienes jur\u00eddicos o al de su entorno familiar m\u00e1s \u00edntimo<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La duda que el t\u00e9rmino \u201cdirecto\u201d incluido en el texto legal pod\u00eda generar, ha quedado sin embargo desplazada con la Ley No.27072 de marzo de 1999 que elimin\u00f3 el t\u00e9rmino referido del Art. 2 del C\u00f3digo Procesal Penal de 1991 y en ese mismo sentido qued\u00f3 redactado el &nbsp;2 del C\u00f3digo Procesal Penal de 1994.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Los delitos a los que puede aplicarse la abstenci\u00f3n por falta de necesidad de pena<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La abstenci\u00f3n por falta de necesidad de la pena opera por igual tanto respecto de los delitos culposos, como respecto de los delitos dolosos en los que la falta de necesidad de pena puede tambi\u00e9n presentarse frente al grave da\u00f1o generado al agente. La norma contenida en el Art. 2 del C\u00f3digo Procesal Penal de 1991 sin embargo no precisa respecto a si el precepto puede aplicarse incluso a delitos graves o esta referido \u00fanicamente a delitos de poca o mediana gravedad. No existe en &nbsp;esta norma un l\u00edmite basado en la gravedad del delito que determine su aplicaci\u00f3n, siendo por tanto posible bajo esta norma procesal su aplicaci\u00f3n incluso para aquellas infracciones penales no comprendidas como de poca o mediana gravedad (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn7\">[7]<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo entendimiento llega la Circular No. 006- 95-MP-FN de noviembre de 1995 y la Resoluci\u00f3n No. 200-2001-CT-MP emitida por el Consejo Transitorio del Ministerio P\u00fablico del 24 de abril del 2001, que aunque t\u00edmidamente,&nbsp; precisan que la abstenci\u00f3n por falta de merecimiento de pena, \u201c<strong>de preferencia<\/strong>\u2026\u201d estar\u00e1 limitada a los delitos de escasa o relativa gravedad, no excluy\u00e9ndose as\u00ed a delitos de mayor gravedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los l\u00edmites del precepto no est\u00e1n dados por la mayor o menor gravedad del delito, sino por los criterios que deben tenerse en cuenta para determinar cuando, frente a un caso de grave da\u00f1o generado al agente, la pena resulte en efecto inapropiada o innecesaria; es desde este punto de vista que los delitos de mayor gravedad resultan con frecuencia excluidos del precepto, porque la compensaci\u00f3n del injusto y la culpabilidad del agente en esos delitos dif\u00edcilmente pueden darse por cumplidos&nbsp; con el grave da\u00f1o sufrido por el agente, no lleg\u00e1ndose por tanto al concepto de falta de necesidad de la pena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tratamiento distinto otorga el Nuevo C\u00f3digo Procesal Penal del 2004 que en los casos de delitos dolosos limita su aplicaci\u00f3n s\u00f3lo a aquellos que est\u00e1n reprimidos con pena privativa de libertad no mayor de cuatro a\u00f1os, similar al tratamiento de la legislaci\u00f3n alemana que estableci\u00f3 igualmente un l\u00edmite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FALTA DE MERECIMIENTO DE PENA&nbsp;&nbsp; .<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los or\u00edgenes de la figura de abstenci\u00f3n de la acci\u00f3n penal por falta de merecimiento de pena se encuentran&nbsp; en el Art. 153 de la Ordenanza Procesal Penal Alemana <a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn8\">[8]<\/a>, en la que el concepto de falta de merecimiento de pena est\u00e1 ligada a la insignificancia del injusto y de la culpabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el derecho nacional, el art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991 ha separado estos dos criterios en dos supuestos:<strong>falta de merecimiento de pena por insignificancia o poca entidad del injusto<\/strong> (Inc.2) y <strong>falta de merecimiento de pena por insignificancia de la culpabilidad<\/strong> (Inc.3), pero haciendo radicar adem\u00e1s su aplicaci\u00f3n en atenci\u00f3n a la protecci\u00f3n de los intereses de la v\u00edctima, con lo que se ha introducido la posibilidad de transacci\u00f3n como instrumento para la soluci\u00f3n de los conflictos penales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Falta de merecimiento de pena por insignificancia del injusto<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> El Inc. 2 del Art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991 establece la posibilidad de la abstenci\u00f3n cuando:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c Cuando se tratare de delitos que por su insignificancia o su poca frecuencia no afecten gravemente el inter\u00e9s p\u00fablico, salvo cuando la pena m\u00ednima supere los dos (02) a\u00f1os de pena privativa de la libertad o se hubiere cometido por un funcionario p\u00fablico en ejercicio de su cargo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El precepto utiliza el t\u00e9rmino insignificancia para referirse a los delitos de escasa o mediana gravedad o tambi\u00e9n llamados delitos-bagatela. Se ha entendido que la escasa o mediana gravedad del delito est\u00e1 delimitada por el monto o cuantum de la pena prevista para el delito en su extremo m\u00ednimo (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn9\">[9]<\/a> ) el cual no debe ser mayor a dos (2) a\u00f1os de pena privativa de la libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este entendimiento la Circular No. 006-95-MP-FN de noviembre de 1995 se\u00f1al\u00f3 en su numeral 9, que lo determinante para la aplicaci\u00f3n del precepto, era que el m\u00ednimo legal de la pena no sea superior a dos a\u00f1os aun cuando el m\u00e1ximo legal de la misma pueda ser mayor. La circular expres\u00f3 as\u00ed: \u201c No impide la aplicaci\u00f3n de esta modalidad de abstenci\u00f3n del ejercicio de la acci\u00f3n penal, el que el marco m\u00e1ximo de la pena supere los dos a\u00f1os, desde que el factor determinante se circunscribe al m\u00ednimo legal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Resoluci\u00f3n No. 200-2001-CT-MP de fecha 24 de abril del a\u00f1o 2001, emitida por el Consejo Transitorio del Ministerio P\u00fablico conten\u00eda sin embargo una directiva o criterio orientador que vino alterar el sentido claro del Inc. 2 del Art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991 al se\u00f1alar que para la aplicaci\u00f3n de \u00e9ste precepto el Fiscal deber\u00e1 tener en cuenta : \u201c Que los delitos considerados, son aquellos que tienen conminado en su extremo m\u00e1ximo, dos a\u00f1os de privaci\u00f3n de libertad\u201d, disposici\u00f3n que evidentemente respondi\u00f3 a un error pues el texto del Art. 2 del C\u00f3digo Procesal Penal volvi\u00f3 nuevamente a respetarse con la daci\u00f3n de la Resoluci\u00f3n No. 266-2001-CT-MP que volv\u00eda a establecer que lo preponderante era el extremo m\u00ednimo de la pena y no el m\u00e1ximo que conten\u00eda la disposici\u00f3n modificada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la insignificancia del delito o de la poca frecuencia, se requiere que la infracci\u00f3n no afecte gravemente el inter\u00e9s p\u00fablico. Esto supone que el precepto est\u00e1 orientado a aquellos delitos en los que el bien jur\u00eddico tutelado no involucre intereses colectivos, sino que est\u00e1 referido a aquellos que afectan el inter\u00e9s particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mismo supuesto es tratado en el nuevo C\u00f3digo Procesal Penal del 2004 bajo el texto siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Cuando se trate de delitos que no afecten gravemente el inter\u00e9s p\u00fablico, salvo cuando el extremo m\u00ednimo de la pena sea superior a los dos a\u00f1os de pena privativa de la libertad, o hubieren sido cometidos por un funcionario p\u00fablico en ejercicio de su cargo\u201d<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Falta de merecimiento de pena por insignificancia de la culpabilidad del agente.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp; <\/strong>El supuesto contenido en el Inc. 3 del Art\u00edculo 2 del C\u00f3digo Procesal Penal de 1991 establece:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a8 Cuando la culpabilidad del agente&nbsp; en la comisi\u00f3n&nbsp; del delito, o su contribuci\u00f3n a la perpetraci\u00f3n del mismo sean m\u00ednimos, salvo que se tratase de un hecho delictuoso cometido por un funcionario p\u00fablico en ejercicio de su cargo\u00a8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ha entendido la m\u00ednima culpabilidad cuando en el caso concreto se presenten circunstancias que determinan una atenuaci\u00f3n considerable de la pena a aplicarse entre los que se encuentran los criterios de determinaci\u00f3n de la pena se\u00f1alados en el C\u00f3digo Penal, como tambi\u00e9n los casos de&nbsp; inculpabilidad incompletas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para determinar la m\u00ednima culpabilidad en el caso concreto, requerir\u00e1 el fiscal contar con todos los elementos que le permitan establecer ello, situaci\u00f3n dif\u00edcil de lograr en la etapa de investigaci\u00f3n preliminar conforme al actual procedimiento regulado por el C\u00f3digo de Procedimiento Penales y m\u00e1s entendible bajo el nuevo modelo procedimental que el C\u00f3digo Procesal Penal del 2004 plantea, en el cual toda la fase de investigaci\u00f3n es asumida por el Ministerio P\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sentido de la m\u00ednima participaci\u00f3n o colaboraci\u00f3n en la perpetraci\u00f3n del delito ha sido reducida a los supuestos de complicidad secundaria conforme a la Circular No. 006-95-MP-FN de 1995 que ha sido en ese aspecto simplemente transcrita en la Resoluci\u00f3n No.200-2001-CT-MP del Consejo Transitorio del Ministerio Publico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ha plateado que el precepto contenido en el Inc. 3&nbsp; solo resulta aplicable a los delitos de nemor y mediana gravedad y que no ser\u00eda conforme a los criterios orientadores de la figura&nbsp; que ella se aplique respecto de los delitos de mayor gravedad (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn10\">[10]<\/a>). La norma procesal contenida en el C\u00f3digo de Procedimientos Penales de 1991 sin embargo no hace tal distingo y pese al car\u00e1cter reglamentario que la Circular 006-95-MP-FN de 1995 y la Resoluci\u00f3n 200-2001-CT-MP de abril del 2001 pretenden, no se ha establecido tampoco en ellas tal limitaci\u00f3n. Conformes con la aplicaci\u00f3n del precepto incluso en el caso de los delitos de mayor gravedad se han pronunciado entre nosotros SAN MARTIN CASTRO y BAMONT ARIAS-TORES (<a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftn11\">[11]<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Nuevo C\u00f3digo Procesal Penal del 2004 para los distritos judiciales en los que ya est\u00e1 en vigencia, plantea sin embargo una restricci\u00f3n, ya que se establece que el supuesto no ser\u00e1 posible cuando se trate de delitos con pena superior a cuatro a\u00f1os de pena privativa de la libertad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La reparaci\u00f3n del da\u00f1o causado como condici\u00f3n para la abstenci\u00f3n de la aci\u00f3n penal por falta de merecimiento de pena<\/strong>.-<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El texto original del Art\u00edculo 2 del C\u00f3digo de Procedimientos Penales de 1991 establece que para los supuesto de falta de merecimiento de pena (Inc.2 e Inc.3) ser\u00e1 necesario adem\u00e1s que el agente hubiere reparado el da\u00f1o ocasionado o exista un acuerdo con la v\u00edctima en ese sentido. La Ley 27072 de marzo del a\u00f1o 1999 modific\u00f3 el texto original y lo dej\u00f3 bajo el siguiente texto: \u201cque el agente hubiere reparado el da\u00f1o ocasionado <em>o exista un acuerdo con la v\u00edctima respecto a la reparaci\u00f3n civil\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que la modificaci\u00f3n hace es precisar que la reparaci\u00f3n a la que el texto alude importa el concepto total de reparaci\u00f3n civil, esto es, reparaci\u00f3n propiamente del da\u00f1o (restituci\u00f3n del bien o el pago de su valor si lo primero no es posible) e indemnizaci\u00f3n de los da\u00f1os y perjuicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La norma procesal no fija pautas sobre c\u00f3mo debe efectuarse esta reparaci\u00f3n, planteando la norma dos supuestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reparaci\u00f3n puede ser un acto espont\u00e1neo del agente sin intervenci\u00f3n alguna de la v\u00edctima, en cuyo caso el Fiscal, para los efectos de proceder a la abstenci\u00f3n del ejercicio de la acci\u00f3n penal debe precisar si lo entregado o pagado en su defecto, constituye una efectiva reparaci\u00f3n del da\u00f1o. En un intento por reglamentar esta posibilidad, la Circular No. 006-95-FN-MP de 1995 y la Resoluci\u00f3n No. 200-2001-CT-MP del a\u00f1o 2001 establecen una diligencia de conciliaci\u00f3n en la que invitar\u00e1 a las partes en conflicto a ponerse de acuerdo sobre el monto de la reparaci\u00f3n o en su defecto podr\u00e1 establecer prudencialmente el que corresponda conforme a los criterios que se\u00f1alan los Arts. 95 a 95 del C\u00f3digo Penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reparaci\u00f3n puede tambi\u00e9n ser el producto de una transacci\u00f3n entre las partes en conflicto y a ello se refiere la norma cuando se\u00f1ala \u201cque exista un acuerdo con la v\u00edctima respecto a la reparaci\u00f3n civil\u201d. La Circular No. 006-95-FN-MP de 1995 y la Resoluci\u00f3n No. 200-2001-CT-MP del a\u00f1o 2001 presentan en este extremo una grave contradicci\u00f3n con el texto de la ley y la naturaleza de la transacci\u00f3n a la que hace referencia el texto procesal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La norma procesal en referencia permite la transacci\u00f3n para los efectos de determinar la reparaci\u00f3n civil proveniente del delito, criterio que adem\u00e1s es recogido en el C\u00f3digo Civil y que convierte a estos pactos en ley entre las partes; sin embargo, las directivas en referencia permiten al Fiscal elevar o disminuir el monto de la reparaci\u00f3n civil que las partes hubieren libremente fijado. Ciertamente esta es una disposici\u00f3n jur\u00eddicamente inaplicable porque se opone al texto de la Ley procesal y contradice la naturaleza de la transacci\u00f3n a la que hace referencia, pero en tanto existan, al ser emitidos por \u00f3rganos de gobierno del Ministerio P\u00fablico,&nbsp; se convertir\u00e1n en elementos que impedir\u00e1n la aplicaci\u00f3n del precepto en el sentido claro de la norma procesal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La transacci\u00f3n extrajudicial como instrumento para la soluci\u00f3n de los conflictos penales<\/strong>.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Cuando la norma procesal ligo la abstenci\u00f3n de la acci\u00f3n penal por falta de merecimiento de pena &nbsp;a la necesidad de reparaci\u00f3n del da\u00f1o o acuerdo sobre la reparaci\u00f3n civil,&nbsp; introdujo t\u00edmidamente la posibilidad de la transacci\u00f3n como instrumento para la soluci\u00f3n de los conflictos penales en los delitos de &nbsp;menor y m\u00ednima gravedad en los que solo se han afectado intereses privados.&nbsp; Ciertamente la transacci\u00f3n sobre la reparaci\u00f3n civil no determina por si sola la soluci\u00f3n del conflicto, pero constituye un elemento importante para la decisi\u00f3n que corresponde al Fiscal y sobre todo, genera un mecanismo r\u00e1pido para el resarcimiento del da\u00f1o a la v\u00edctima, que es lo que com\u00fanmente motiva la continuidad de la acci\u00f3n penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">_________________________________________________________<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los art\u00edculos y comentarios de Derecho Penal y Procesal Penal publicados en esta p\u00e1gina, buscan contribuir al entendimiento del derecho, preparado por abogados penalistas y orientados al p\u00fablico en general en el lenguaje m\u00e1s pr\u00e1ctico posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VASQUEZ | TAFUR<\/strong>&nbsp;Abogados<br>Estudio de Abogados Lima Per\u00fa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref1\">[1]<\/a>.- BAUMANN Jurgen, Derecho Procesal Penal, Ediciones Depalma, Buenos Aires, 1986, P\u00e1g.62.<\/p>\n\n\n\n<div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref2\">[2]<\/a>.- Seg\u00fan MAIER, Julio, citado por Ra\u00fal Pe\u00f1a Cabrera, Terminaci\u00f3n Anticipada del Proceso, Ed. Grijley, Lima 1995, P\u00e1g. 55.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref3\">[3]<\/a> .- Art. 60 del C\u00f3digo Penal Alem\u00e1n dispone la dispensa de pena \u201ccuando las consecuencias del delito que han&nbsp; alcanzado al reo son tan graves que ser\u00eda evidentemente un error la imposici\u00f3n de una pena\u201d. En Jescheck, Tratado de Derecho Penal, Tomo II, Ed. Bosch, Barcelona 1981, P\u00e1g. 1177.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref4\">[4]<\/a> .- Jescheck, Ob. Cit. P\u00e1g. 1178.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref5\">[5]<\/a> .- En este sentido tambi\u00e9n HASSEMER, Winfried, en art\u00edculo \u201c La Renuncia a la Pena como instrumento pol\u00edtico criminal\u201d publicado en Pol\u00edtica Criminal y Reforma del Derecho Penal, Ed, Temis, Bogot\u00e1, Colombia 1982, P\u00e1g. 216.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref6\">[6]<\/a> .- S\u00c1NCHEZ VELARDE, Pablo, Ob.Cit. P\u00e1g. 154.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref7\">[7]<\/a> .- En igual sentido S\u00c1NCHEZ VELARDE, Pablo, Ob.Cit. P\u00e1g. 155<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref8\">[8]<\/a> .- En Jescheck, Ob. Cit. P\u00e1g. 1176 y HASSEMER, Ob. Cit. P\u00e1g.220.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref9\">[9]<\/a> .- As\u00ed S\u00c1NCHEZ VELARDE, Pablo, Ob.Cit.P\u00e1g.158.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref10\">[10]<\/a> .- SANCHEZ VELARDE, Pablo, Ob. Cit. P\u00e1g.160.<\/p>\n<\/div>\n<div>\n<p style=\"text-align: justify;\"><a title=\"\" href=\"https:\/\/vasquezabogados.com\/estudio\/articulos\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#_ftnref11\">[11]<\/a> .- SAN MARTIN CASTRO, Cesar, Derecho Procesal Penal, Vol.I Ed. Grijley, Lima 1999, P\u00e1g.233 y BRAMONT ARIAS-TORES, Luis Alberto, en art\u00edculo \u00a8Modificaci\u00f3n del Principio de Oportunidad\u00a8 publicado en Revista GACETA JUR\u00cfDICA,<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Por Marlio V\u00e1squez V\u00e1squezSocio de VASQUEZ | TAFUR AbogadosMiembro de Peruvian Legal Network &nbsp;Utilidad. El presente comentario explica las posibilidades de archivamiento de una denuncia o proceso penal en base a un acuerdo entre las partes involucradas, logrando que la voluntad entre v\u00edctima y agresor pongan fin a la acci\u00f3n penal que com\u00fanmente se entend\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[256],"tags":[276,290],"class_list":["post-1011","post","type-post","status-publish","format-standard","hentry","category-derecho-penal-y-procesal-penal","tag-abogado-penalista","tag-proceso-penal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados<\/title>\n<meta name=\"description\" content=\"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados\" \/>\n<meta property=\"og:description\" content=\"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Vasquez I Tafur Abogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VASQUEZ-TAFUR-Abogados-244262572262476\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-13T04:36:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T15:34:38+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\"},\"headline\":\"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD\",\"datePublished\":\"2013-02-13T04:36:28+00:00\",\"dateModified\":\"2020-06-23T15:34:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/\"},\"wordCount\":4568,\"commentCount\":0,\"keywords\":[\"abogado penalista\",\"proceso penal\"],\"articleSection\":[\"Derecho Penal y Procesal Penal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/\",\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/\",\"name\":\"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#website\"},\"datePublished\":\"2013-02-13T04:36:28+00:00\",\"dateModified\":\"2020-06-23T15:34:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\"},\"description\":\"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2013\\\/02\\\/13\\\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#website\",\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/\",\"name\":\"Vasquez I Tafur Abogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados","description":"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/","og_locale":"es_ES","og_type":"article","og_title":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados","og_description":"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal","og_url":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/","og_site_name":"Vasquez I Tafur Abogados","article_publisher":"https:\/\/www.facebook.com\/VASQUEZ-TAFUR-Abogados-244262572262476","article_published_time":"2013-02-13T04:36:28+00:00","article_modified_time":"2020-06-23T15:34:38+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#article","isPartOf":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/"},"author":{"name":"admin","@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b"},"headline":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD","datePublished":"2013-02-13T04:36:28+00:00","dateModified":"2020-06-23T15:34:38+00:00","mainEntityOfPage":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/"},"wordCount":4568,"commentCount":0,"keywords":["abogado penalista","proceso penal"],"articleSection":["Derecho Penal y Procesal Penal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/","url":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/","name":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD &#8211; Vasquez I Tafur Abogados","isPartOf":{"@id":"https:\/\/vasquezabogados.com\/estudio\/#website"},"datePublished":"2013-02-13T04:36:28+00:00","dateModified":"2020-06-23T15:34:38+00:00","author":{"@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b"},"description":"Explica posibilidades de archivamiento de la acci\u00f3n penal en base a un acuerdo entre las partes logrando que la voluntad ponga fin a la controversia penal","breadcrumb":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vasquezabogados.com\/estudio\/2013\/02\/13\/abstencion-del-ejercicio-de-la-accion-penal-principio-de-oportunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vasquezabogados.com\/estudio\/"},{"@type":"ListItem","position":2,"name":"ABSTENCION DEL EJERCICIO DE LA ACCION PENAL \u2013 PRINCIPIO DE OPORTUNIDAD"}]},{"@type":"WebSite","@id":"https:\/\/vasquezabogados.com\/estudio\/#website","url":"https:\/\/vasquezabogados.com\/estudio\/","name":"Vasquez I Tafur Abogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vasquezabogados.com\/estudio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/vasquezabogados.com\/estudio\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/comments?post=1011"}],"version-history":[{"count":5,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1011\/revisions"}],"predecessor-version":[{"id":1511,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1011\/revisions\/1511"}],"wp:attachment":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/media?parent=1011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/categories?post=1011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/tags?post=1011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}