{"id":1005,"date":"2012-05-14T04:32:32","date_gmt":"2012-05-14T04:32:32","guid":{"rendered":"http:\/\/vasquezabogados.com\/estudio\/?p=1005"},"modified":"2016-04-23T05:18:26","modified_gmt":"2016-04-23T05:18:26","slug":"el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2","status":"publish","type":"post","link":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/","title":{"rendered":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Por Reimundo Urcia Bernab\u00e9<br \/>\n<\/strong>Responsable del \u00e1rea de Investigaciones y Peritajes de\u00a0 VASQUEZ | TAFUR\u00a0Abogados<br \/>\nPerito Judicial Grafot\u00e9cnico de la Corte Superior de Justicia de Lima-Per\u00fa<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>INTRODUCCI\u00d3N<\/strong><\/p>\n<p style=\"text-align: justify;\">Sabido es, que la confianza y concertaci\u00f3n de las partes, produce la acci\u00f3n de firmar un documento en blanco, que es aprovechado para alterar el acuerdo primigenio, por ello, muchas veces al analizar un documento cuestionado decimos que si el texto es aut\u00e9ntico, la firma tambi\u00e9n lo es y de seguro muy \u201csuelto de huesos\u201d exclamamos \u00a1este documento es aut\u00e9ntico! olvidando que el abuso de firma en blanco, sucede cuando \u201cel autor del fraude recibe de la v\u00edctima un documento firmado en blanco que le es entregado voluntariamente y con una finalidad exclusiva, pero que el tenedor abusando de ello, llena el documento insertando declaraciones u obligaciones de car\u00e1cter patrimonial perjudiciales para el firmante o un tercero\u201d. Como vemos, este fraude constituye un abuso de confianza de una de las partes, que se aprovecha del espacio libre y de la firma aut\u00e9ntica, para adecuar un texto caprichoso, el mismo que resulta falso, agraviando al titular de la signatura.<\/p>\n<p style=\"text-align: justify;\">Qu\u00e9 hacer entonces, cuando el documento presenta una disposici\u00f3n irregular de la firma con relaci\u00f3n al texto, (alejamiento exagerado del texto falso referente a la firma), debemos solo indicar a la autoridad judicial esta observaci\u00f3n o seguir investigando y contrastando otros detalles, teniendo en cuenta que la pericia grafot\u00e9cnica y documentosc\u00f3pica, es eminentemente comparativa. Definitivamente debemos de investigar y recordar las expresiones indicadas por Albert Osborn: \u201cUna simple firma puede representar miles y aun millones de d\u00f3lares; y cuando cada uno de los trazos de pocas letras genuinas puedan representar decenas y hasta ciento de miles de d\u00f3lares, es natural que cada parte, cada detalle de esta producci\u00f3n humana tan peque\u00f1a, tanto de la mano como la del cerebro, sea estudiada y escudri\u00f1ada en todas las formas posibles\u201d.<\/p>\n<p style=\"text-align: justify;\">Al respecto, se nombrar\u00e1 algunas t\u00e9cnicas o herramientas que no podr\u00e1 olvidar el perito para el reconocimiento pericial del abuso de firma en blanco, tales como:<\/p>\n<p style=\"text-align: justify;\">\u2013 Orden de ejecuci\u00f3n de trazos o prelaci\u00f3n de trazos,<br \/>\n\u2013 Historial signatural,<br \/>\n\u2013 Reflejo de evitaci\u00f3n,<br \/>\n\u2013 Disposici\u00f3n y distribuci\u00f3n de m\u00e1rgenes,<br \/>\n\u2013 Emplazamiento o redacci\u00f3n escritural,<br \/>\n\u2013 Verificaci\u00f3n de zonas de estimulo y reflejos condicionados. (emplazamiento o acomodamiento de la firma sobre la l\u00ednea de pauta, espacios en blanco, recuadros o formatos espec\u00edficos)<\/p>\n<p style=\"text-align: justify;\">El presente art\u00edculo pondr\u00e1 \u00e9nfasis en las l\u00edneas precedentes, referido al conocimiento de los procesos psicomotrices de la firma, verificaci\u00f3n de las zonas de estimulo, posici\u00f3n constante o acomodamiento de la firma sobre la superficie receptora y los reflejos condicionados.<\/p>\n<p style=\"text-align: justify;\"><strong>CASU\u00cdSTICA PERICIAL DOCUMENTOSC\u00d3PICA<\/strong><\/p>\n<p style=\"text-align: justify;\">La autoridad judicial tuvo a bien nombrarme junto con otro perito, quien advirti\u00f3 que en este caso ya se hab\u00eda formulado un dictamen pericial, en donde los peritos se\u00f1alaban que la firma trazada en la minuta de compraventa de un inmueble valorizado en \u201cmiles de miles\u201d de d\u00f3lares americanos, proven\u00eda del pu\u00f1o gr\u00e1fico del titular y que no exist\u00eda ning\u00fan tipo de fraude o alteraciones dolosas, adem\u00e1s que carec\u00eda de las condiciones f\u00edsicas del denominado \u201ccruce de trazos\u201d, no existiendo contacto alguno entre los trazos de la firma del titular y los textos mecanogr\u00e1ficos, cuya observaci\u00f3n microsc\u00f3pica de los puntos de coincidencia, hubiera podido evidenciar la prelaci\u00f3n de trazos y consecuentemente su orden de ejecuci\u00f3n. Por lo que de primera intenci\u00f3n le record\u00e9 que no debemos condicionarnos a las expresiones de otros peritos o a los contenidos de dict\u00e1menes periciales que se relacionen a la muestra controvertida, sino que nos dediquemos a investigar con responsabilidad t\u00e9cnica y cient\u00edfica, enunciando en forma objetiva y demostrativa las caracter\u00edsticas relevantes del documento materia de pericia, finalmente le replique: \u201cno creas todo lo que dicen, investiga\u201d.<\/p>\n<p style=\"text-align: justify;\">Teniendo como premisa el enunciado precedente, nos abocamos al estudio de la muestra cuestionada, en aplicaci\u00f3n de los m\u00e9todos de an\u00e1lisis, s\u00edntesis y de validez documental, que consiste en cinco operaciones progresivas: observaci\u00f3n, descripci\u00f3n, selecci\u00f3n, cotejo y juicio valorativo comprob\u00e1ndose que el contenido del documento incriminado representaba una minuta de compra venta de un inmueble, redactada en dos hojas blancas con m\u00e1quina de escribir mec\u00e1nica, cuya \u00faltima p\u00e1gina segmentada en el tercio inferior, registraba el trazado de la firma de \u201cE.B\u201d; cabe anotar que la zona del corte, advert\u00eda residuos de tinta azul compatible con estampado de sellos, los mismos que fueron perennizados mediante tomas fotogr\u00e1ficas, esto obviamente era evidente, pero, luego de haber efectuado el seguimiento visual de los elementos diferenciales del documento, (papel, formato, disposici\u00f3n y distribuci\u00f3n de los caracteres dactilografiados, m\u00e1rgenes, marcas de agua, estampados de sellos, interlineado, etc), pusimos atenci\u00f3n a la firma que aparec\u00eda al final del texto, verific\u00e1ndose un alejamiento inusual entre la \u00faltima l\u00ednea de los caracteres mecanogr\u00e1ficos (referido a la fecha del documento) y el trazado de la signatura, cuya distancia o espaciado era realmente exagerado.<\/p>\n<p style=\"text-align: justify;\">Hasta ah\u00ed nos indicaba un alentador indicio, pues recordemos que tanto el texto como la firma ocupan normalmente un espacio o \u00e1rea determinada en un documento; pero tambi\u00e9n es cierto que no existen normas sobre el trazado de la firma al pie del documento y entonces, \u00bfc\u00f3mo probar el abuso de firma en blanco? \u00bf c\u00f3mo demostrar ante la autoridad judicial que la firma fue trazada con anterioridad al texto mecanogr\u00e1fico?.<\/p>\n<p style=\"text-align: justify;\">Lo aconsejable es reunir muestras id\u00f3neas de comparaci\u00f3n y en lo posible, con similares caracter\u00edsticas a la muestra cuestionada, es decir, si nos encontramos con texto dactilografiado en papel blanco de tama\u00f1o DIN A4, y con la \u00faltima l\u00ednea del texto referida a la fecha, pues entonces recurriremos a uno semejante, teniendo en cuenta la morfolog\u00eda de la \u00faltima l\u00ednea del texto con respecto a la signatura del titular, pues bien, se efectu\u00f3 un cotejo y examen exhaustivo de las firmas indubitadas, aut\u00e9nticas y \u00a1aleluya!, sorpresa, la firma atribuida a \u201cE.B\u201d, estaba trazada cerca de la \u00faltima l\u00ednea de rengl\u00f3n mecanogr\u00e1fico, adoptando una posici\u00f3n constante al revisar 25 muestras, ubicaci\u00f3n que, por supuesto, se diferenciaban con la suscripci\u00f3n del documento cuestionado.<\/p>\n<p style=\"text-align: justify;\"><strong>FUNDAMENTO T\u00c9CNICO CIENT\u00cdFICO<\/strong><\/p>\n<p style=\"text-align: justify;\">LA FIRMA GENERA RESPUESTAS CONDICIONADAS HABITUALES E INCONSCIENTES A BASE DE LA REPETICI\u00d3N Y ASOCIACI\u00d3N DE ESTIMULOS GRAFICOS<\/p>\n<p style=\"text-align: justify;\">La investigaci\u00f3n realizada en personas con habilidad en la suscripci\u00f3n, nos permite aseverar que la acci\u00f3n signatural, se hace habitual e inconsciente, a base de m\u00faltiples asociaciones entre ciertas situaciones y ciertas reacciones, como es, el reiterado ejercicio de firmar y las condiciones similares que presenta el documento, generando con ello las respuestas condicionadas.<\/p>\n<p style=\"text-align: justify;\">Estas respuestas condicionadas desarrollado por el fisi\u00f3logo ruso J.P Pavlov, quien tambi\u00e9n emple\u00f3 el t\u00e9rmino \u201creflejo condicionado\u201d, podr\u00eda explicar todo h\u00e1bito y todo aprendizaje de la acci\u00f3n gr\u00e1fica.<\/p>\n<p style=\"text-align: justify;\">Enseguida se har\u00e1 algunas precisiones que tienen relevancia en el reconocimiento del fraude por abuso de firma en blanco:<\/p>\n<p style=\"text-align: justify;\"><strong>1. Conocimiento de los procesos psicomotrices de la firma<\/strong><\/p>\n<p style=\"text-align: justify;\">Haciendo una s\u00edntesis de lo publicado en el libro verificaci\u00f3n de firmas, debemos de indicar que durante el acto de firmar ocurren ciertos mecanismos psicomotrices que todo perito deber\u00e1 conocerlo, tales como:<\/p>\n<p style=\"text-align: justify;\">a. Mecanismo intelectual<br \/>\nb. Mecanismo de aprehensi\u00f3n,<br \/>\nc. Mecanismo de inscripci\u00f3n signatural,<br \/>\nd. Mecanismo de coordinaci\u00f3n o de coexistencia de grafismos<br \/>\ne. Mecanismo de ubicaci\u00f3n<\/p>\n<p style=\"text-align: justify;\">Al respecto, recordaremos que \u201clas im\u00e1genes automatizadas provienen del cerebro y esencialmente del cerebelo, pues la actividad neuronal bioel\u00e9ctrica env\u00eda \u00f3rdenes a cada uno de los m\u00fasculos ejecutantes de la signatura\u201d, afirm\u00e1ndose que la percepci\u00f3n y conservaci\u00f3n de la imagen representativa individual motiva el reconocimiento y evocaci\u00f3n de la imagen visual, es decir que toda persona mantiene un recuerdo o capacidad de revivir lo conservado y despertar o darle vida al registro de la imagen que fue adquirida por nuestro cerebro, evocando una imagen cinest\u00e9sica, (movimientos musculares) reflejada por la repetici\u00f3n de los desenvolvimientos gr\u00e1ficos juntamente con ciertas zonas de estimulo que aparecen en la superficie escritora, motivando reflejos condicionados o im\u00e1genes automatizadas durante la acci\u00f3n din\u00e1mica individual.<\/p>\n<p style=\"text-align: justify;\"><strong>2. Verificaci\u00f3n de las zonas de estimulo gr\u00e1fico<\/strong><\/p>\n<p style=\"text-align: justify;\">La firma como conjunto diferenciado de trazos, que realiza una persona en forma inconsciente, espont\u00e1nea, especializada y frecuente, mantiene una acci\u00f3n din\u00e1mica peculiar cuando est\u00e1 frente a ciertas zonas de estimulo, que hacen del titular un acondicionamiento permanente y usual, propia de su habilidad signatural y diferenciaci\u00f3n grafointrinseca. El estimulo es la incitaci\u00f3n a una reacci\u00f3n directa del \u00f3rgano receptor, y esto sucede por la evocaci\u00f3n de la imagen visual y cinest\u00e9sica de la persona al momento de ejecutar la firma.<\/p>\n<p style=\"text-align: justify;\">Las zonas de estimulo, es el conjunto de elementos referenciales, que sirven de gu\u00eda para el asentamiento de la firma sobre la superficie escriptora, (Jos\u00e9 Luis Balbuena Balmaceda los llama puntos referenciales exteriores).<\/p>\n<p style=\"text-align: justify;\">Es preciso hacer presente que las zonas de est\u00edmulo, pueden estar representadas por el propio papel en blanco, as\u00ed como por los espacios restringidos de la firma y el dise\u00f1o conocido como formato, el mismo que puede haber sido originado por la redacci\u00f3n del texto manuscrito, mecanografiado o el propio impreso, que sirve para distribuir y disponer los trazos de la firma.<\/p>\n<p style=\"text-align: justify;\">Entre las zonas de est\u00edmulo signatural podemos encontrar las siguientes:<\/p>\n<p style=\"text-align: justify;\">\u2022 papel blanco o campo gr\u00e1fico en blanco<br \/>\n\u2022 l\u00edneas de rengl\u00f3n o de pauta impresa en el papel<br \/>\n\u2022 recuadros o rect\u00e1ngulos para la firma<br \/>\n\u2022 espacios restringidos para la firma<br \/>\n\u2022 ante firmas<br \/>\n\u2022 post firmas<br \/>\n\u2022 ultima l\u00ednea del texto manuscrito o mecanogr\u00e1fico<br \/>\n\u2022 ultimo p\u00e1rrafo de texto<br \/>\n\u2022 formato preestablecido o dise\u00f1o impreso<br \/>\n\u2022 formato motivado por la propia redacci\u00f3n del texto manuscrito o mecanogr\u00e1fico.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Verificaci\u00f3n de la posici\u00f3n constante<\/strong><\/p>\n<p style=\"text-align: justify;\">La posici\u00f3n constante est\u00e1 dada por el deseo, intenci\u00f3n y b\u00fasqueda de est\u00edmulos (elementos referenciales) del titular al momento de ejecutar su acci\u00f3n gr\u00e1fica, para luego adoptar una ubicaci\u00f3n y posicionamiento visual constante, debido a la frecuencia (repetici\u00f3n) y reflejos condicionados en el asentamiento de la firma.<\/p>\n<p style=\"text-align: justify;\">Podemos encontrar ciertas caracter\u00edsticas de la posici\u00f3n constante, las cuales se detallan a continuaci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">\u2022 relaci\u00f3n o ubicaci\u00f3n de la firma con la superficie escritora o papel en blanco<br \/>\n\u2022 relaci\u00f3n o ubicaci\u00f3n de la firma con el formato o espacio preestablecido<br \/>\n\u2022 firma reducida o ampliada respecto al espacio restringido para la firma<br \/>\n\u2022 firma con espacio gr\u00e1fico al inicio de la l\u00ednea de pauta<br \/>\n\u2022 firma con espacio gr\u00e1fico al final de la l\u00ednea de pauta<br \/>\n\u2022 firma con espacios gr\u00e1ficos en las zonas laterales que enuncian su ubicaci\u00f3n en la zona central<br \/>\n\u2022 firma sobrealzada a la l\u00ednea de rengl\u00f3n (pauta)<br \/>\n\u2022 firma razante o sobre la l\u00ednea de pauta<br \/>\n\u2022 firma que sobrepasa o entrecruza la l\u00ednea de pauta<br \/>\n\u2022 firma ascendente respecto de la l\u00ednea de pauta<br \/>\n\u2022 firma que cruza los trazos de la \u00faltima l\u00ednea del texto<br \/>\n\u2022 firma con espacio reducido a la \u00faltima l\u00ednea del texto<br \/>\n\u2022 firma que cruza la antefirma o postfirma<br \/>\n\u2022 firma que reserva espacio en la antefirma o post firma<\/p>\n<p style=\"text-align: justify;\"><strong>4. Verificaci\u00f3n de los reflejos condicionados<\/strong><\/p>\n<p style=\"text-align: justify;\">La acci\u00f3n din\u00e1mica individual es el resultado de una compleja variedad de h\u00e1bitos que permiten individualizar al titular y que resultan del automatismo gr\u00e1fico, as\u00ed como de los factores ps\u00edquicos y org\u00e1nicos de la persona. El reflejo no es m\u00e1s que la respuesta innata, simple y espec\u00edfica a una zona de est\u00edmulo (elementos referenciales) que act\u00faa sobre un \u00f3rgano receptor, es as\u00ed que toda persona acondiciona su firma al espacio gr\u00e1fico restringido debido a los reflejos gr\u00e1ficos condicionados.<\/p>\n<p style=\"text-align: justify;\">Recordaremos al maestro colombiano Alberto Posada Angel, que en su obra Grafolog\u00eda y Grafopatolog\u00eda, se\u00f1ala lo siguiente:<\/p>\n<p style=\"text-align: justify;\">\u201cun sujeto que normalmente escribe con una letra de tama\u00f1o grande, vi\u00e9ndose frente a un espacio peque\u00f1o, necesariamente reduce su sistema-condici\u00f3n, a fin de ajustarlo al medio contemplado. frente a este principio, el perito analiza las diferencias de medio y de modo y busca las constantes y las relaciones que act\u00faan en los diversos casos, anotando los puntos de contacto que vienen a establecer la uniprocedencia fundamental. A \u00e9l no le basta encontrar meras coincidencias; s\u00f3lo se contenta cuando halla el total de las propiedades y de los caracteres en raz\u00f3n de su equivalencia. Es por esto por lo que todo examen grafot\u00e9cnico exige una doble tarea, la de an\u00e1lisis y la de s\u00edntesis; por la primera se separa y se selecciona y por la segunda se integra y se totaliza\u201d.<\/p>\n<p style=\"text-align: justify;\">Finalmente ratificar el fundamento t\u00e9cnico cient\u00edfico: \u201cLa Firma genera respuestas condicionadas habituales e inconscientes a base de la repetici\u00f3n y asociaci\u00f3n de est\u00edmulos gr\u00e1ficos\u201d.<\/p>\n<p style=\"text-align: justify;\">Anotemos, que siempre y cuando el titular logre una asociaci\u00f3n repetida de la evocaci\u00f3n de la imagen cinest\u00e9sica de la firma con elementos referenciales que presenta la superficie escritora (papel en blanco, l\u00ednea de pauta, recuadros o formatos espec\u00edficos, ultima l\u00ednea del texto manuscrito o mecanogr\u00e1fico, entre otros) que sirven de gu\u00eda para el emplazamiento, acomodamiento y asentamiento de la firma, obtendr\u00e1 como resultado una posici\u00f3n constante. Es decir, permitir\u00e1 que ciertas reacciones (reflejos condicionados) y ciertas situaciones (zonas de estimulo) sean similares y frecuentes, enunci\u00e1ndose con ello una nueva dominante gr\u00e1fica para la soluci\u00f3n de ciertos casos, como el reconocimiento del abuso de firma en blanco y las propias falsificaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Reimundo Urcia Bernab\u00e9 Responsable del \u00e1rea de Investigaciones y Peritajes de\u00a0 VASQUEZ | TAFUR\u00a0Abogados Perito Judicial Grafot\u00e9cnico de la Corte Superior de Justicia de Lima-Per\u00fa \u00a0 INTRODUCCI\u00d3N Sabido es, que la confianza y concertaci\u00f3n de las partes, produce la acci\u00f3n de firmar un documento en blanco, que es aprovechado para alterar el acuerdo primigenio, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[256],"tags":[],"class_list":["post-1005","post","type-post","status-publish","format-standard","hentry","category-derecho-penal-y-procesal-penal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;\" \/>\n<meta property=\"og:description\" content=\"Por Reimundo Urcia Bernab\u00e9 Responsable del \u00e1rea de Investigaciones y Peritajes de\u00a0 VASQUEZ | TAFUR\u00a0Abogados Perito Judicial Grafot\u00e9cnico de la Corte Superior de Justicia de Lima-Per\u00fa \u00a0 INTRODUCCI\u00d3N Sabido es, que la confianza y concertaci\u00f3n de las partes, produce la acci\u00f3n de firmar un documento en blanco, que es aprovechado para alterar el acuerdo primigenio, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Vasquez I Tafur Abogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VASQUEZ-TAFUR-Abogados-244262572262476\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-14T04:32:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-23T05:18:26+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\"},\"headline\":\"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL\",\"datePublished\":\"2012-05-14T04:32:32+00:00\",\"dateModified\":\"2016-04-23T05:18:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/\"},\"wordCount\":2366,\"commentCount\":0,\"articleSection\":[\"Derecho Penal y Procesal Penal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/\",\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/\",\"name\":\"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#website\"},\"datePublished\":\"2012-05-14T04:32:32+00:00\",\"dateModified\":\"2016-04-23T05:18:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/2012\\\/05\\\/14\\\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#website\",\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/\",\"name\":\"Vasquez I Tafur Abogados\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/#\\\/schema\\\/person\\\/4181885f3a3d5119421b30b53cb6e61b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/vasquezabogados.com\\\/estudio\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/","og_locale":"es_ES","og_type":"article","og_title":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;","og_description":"Por Reimundo Urcia Bernab\u00e9 Responsable del \u00e1rea de Investigaciones y Peritajes de\u00a0 VASQUEZ | TAFUR\u00a0Abogados Perito Judicial Grafot\u00e9cnico de la Corte Superior de Justicia de Lima-Per\u00fa \u00a0 INTRODUCCI\u00d3N Sabido es, que la confianza y concertaci\u00f3n de las partes, produce la acci\u00f3n de firmar un documento en blanco, que es aprovechado para alterar el acuerdo primigenio, [&hellip;]","og_url":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/","og_site_name":"Vasquez I Tafur Abogados","article_publisher":"https:\/\/www.facebook.com\/VASQUEZ-TAFUR-Abogados-244262572262476","article_published_time":"2012-05-14T04:32:32+00:00","article_modified_time":"2016-04-23T05:18:26+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/#article","isPartOf":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/"},"author":{"name":"admin","@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b"},"headline":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL","datePublished":"2012-05-14T04:32:32+00:00","dateModified":"2016-04-23T05:18:26+00:00","mainEntityOfPage":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/"},"wordCount":2366,"commentCount":0,"articleSection":["Derecho Penal y Procesal Penal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/","url":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/","name":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL &#8211; Vasquez I Tafur Abogados &#8211;","isPartOf":{"@id":"https:\/\/vasquezabogados.com\/estudio\/#website"},"datePublished":"2012-05-14T04:32:32+00:00","dateModified":"2016-04-23T05:18:26+00:00","author":{"@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b"},"breadcrumb":{"@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vasquezabogados.com\/estudio\/2012\/05\/14\/el-abuso-de-firma-en-blanco-y-su-reconocimiento-pericial-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/vasquezabogados.com\/estudio\/"},{"@type":"ListItem","position":2,"name":"EL ABUSO DE FIRMA EN BLANCO Y SU RECONOCIMIENTO PERICIAL"}]},{"@type":"WebSite","@id":"https:\/\/vasquezabogados.com\/estudio\/#website","url":"https:\/\/vasquezabogados.com\/estudio\/","name":"Vasquez I Tafur Abogados","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vasquezabogados.com\/estudio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vasquezabogados.com\/estudio\/#\/schema\/person\/4181885f3a3d5119421b30b53cb6e61b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/216cf7bced2d771045096aefbe16ae6ccfb6e60d3d5bf76ee889a4e395f708b6?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/vasquezabogados.com\/estudio\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/comments?post=1005"}],"version-history":[{"count":2,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1005\/revisions"}],"predecessor-version":[{"id":1195,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/posts\/1005\/revisions\/1195"}],"wp:attachment":[{"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/media?parent=1005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/categories?post=1005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vasquezabogados.com\/estudio\/wp-json\/wp\/v2\/tags?post=1005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}